{"id":5275,"date":"2025-04-28T17:43:03","date_gmt":"2025-04-28T17:43:03","guid":{"rendered":"https:\/\/bio.ufpr.br\/cbio\/?page_id=5275"},"modified":"2026-02-05T14:53:16","modified_gmt":"2026-02-05T14:53:16","slug":"procedimentos","status":"publish","type":"page","link":"https:\/\/bio.ufpr.br\/cbio\/procedimentos\/","title":{"rendered":"Procedimentos"},"content":{"rendered":"<h3>Dispensa de frequ\u00eancia<\/h3>\n<p><a href=\"https:\/\/bio.ufpr.br\/cbio\/wp-content\/uploads\/sites\/3\/2025\/03\/Res.-37-97-CEPE.pdf\">Resolu\u00e7\u00e3o 37\/97 &#8211; CEPE<\/a><\/p>\n<p style=\"padding-left: 40px\"><strong>Art. 80<\/strong> &#8211;<strong>N\u00e3o haver\u00e1 abono de faltas, qualquer que tenha sido a raz\u00e3o da aus\u00eancia<\/strong>.<br \/>\n<strong>Art. 81<\/strong> -O coordenador do curso, de comum acordo com o(s) professor(es) ministrante(s) da(s) disciplina(s) cursada(s) pelo aluno, poder\u00e3o dispensar esporadicamente das aulas regulares o<br \/>\naluno participante de cursos intensivos, simp\u00f3sios, semin\u00e1rios, congressos, aulas extraordin\u00e1rias, e outras atividades similares, sempre que houver correla\u00e7\u00e3o com o seu curso, devendo, em caso de deferimento, ser marcadas presen\u00e7as em todas as aulas e possibilitada a segunda chamada de avalia\u00e7\u00f5es formais que eventualmente ocorrerem no per\u00edodo.<\/p>\n<p style=\"padding-left: 80px\">\u00a7 1\u00ba &#8211; Nos casos em que o aluno necessite de uma manifesta\u00e7\u00e3o pr\u00e9via a respeito de sua pretens\u00e3o, dever\u00e1 o mesmo encaminhar pedido formal \u00e0 coordena\u00e7\u00e3o do curso, a qual, juntamente com o(s) professor(es) da(s) disciplina(s), dever\u00e3o pronunciar-se no prazo de cinco (05) dias \u00fateis contados do recebimento da solicita\u00e7\u00e3o.<br \/>\n\u00a7 2\u00ba &#8211; Encerrado o evento, dever\u00e1 o aluno de imediato apresentar ao professor da disciplina documento comprobat\u00f3rio de sua participa\u00e7\u00e3o no mesmo, a fim de que sejam lan\u00e7adas as presen\u00e7as e marcada a eventual segunda chamada de avalia\u00e7\u00e3o formal.<\/p>\n<p style=\"padding-left: 40px\"><strong>Art. 82<\/strong> -S\u00e3o consideradas atividades universit\u00e1rias regulares as participa\u00e7\u00f5es de alunos nos Jogos Universit\u00e1rios Brasileiros ou de sele\u00e7\u00e3o nacional, de confedera\u00e7\u00f5es ou federa\u00e7\u00f5es<br \/>\nestaduais, e ainda, aquelas de cunho cultural promovidas pela UFPR, nas apresenta\u00e7\u00f5es oficiais, per\u00edodo em que ser\u00e3o marcadas presen\u00e7as em todas as aulas, devendo ser possibilitada a segunda chamada de avalia\u00e7\u00f5es formais que eventualmente ocorrerem.<\/p>\n<p style=\"padding-left: 80px\">\u00a7 1\u00ba &#8211; O aluno dever\u00e1 comunicar formal e previamente ao professor da disciplina a sua participa\u00e7\u00e3o em atividades enquadradas no caput deste artigo.<br \/>\n\u00a7 2\u00ba &#8211; Encerrado o per\u00edodo de afastamento, dever\u00e1 o aluno apresentar documento comprobat\u00f3rio de sua efetiva participa\u00e7\u00e3o, fornecido pela sua federa\u00e7\u00e3o ou confedera\u00e7\u00e3o de desportos ou pela Pr\u00f3-Reitoria respons\u00e1vel pelas atividades culturais, para que sejam registradas as presen\u00e7as e marcada a data da eventual segunda chamada de avalia\u00e7\u00e3o formal.<\/p>\n<p style=\"padding-left: 40px\"><strong>Art. 82-A<\/strong>. Nos termos da lei n\u00ba 13.796\/19, \u00e9 direito do estudante ausentar-se de prova ou de aula marcada para dia em que, segundo os preceitos de sua religi\u00e3o, seja vedado o exerc\u00edcio de<br \/>\ntais atividades. (Inclu\u00eddo pela <a href=\"https:\/\/bio.ufpr.br\/cbio\/wp-content\/uploads\/sites\/3\/2025\/05\/RESOLUCAO-No-42-22-CEPE.pdf\">Resolu\u00e7\u00e3o n\u00ba 42\/22-CEPE<\/a>)<\/p>\n<p style=\"padding-left: 80px\">\u00a71\u00b0 Para usufruir de tal direito, o discente deve dirigir requerimento com 5 (cinco) dias \u00fateis de anteced\u00eancia da prova ou aula em que se ausentar\u00e1, conforme modelo padr\u00e3o disponibilizado pela UFPR aos departamentos ou unidades acad\u00eamicas equivalentes que ofertem a unidade curricular\/disciplina envolvida. (Inclu\u00eddo pela <a href=\"https:\/\/bio.ufpr.br\/cbio\/wp-content\/uploads\/sites\/3\/2025\/05\/RESOLUCAO-No-42-22-CEPE.pdf\">Resolu\u00e7\u00e3o n\u00ba 42\/22-CEPE<\/a>)<br \/>\n\u00a72\u00b0 Em caso de aus\u00eancia em prova ou aula amparada pelo caput do artigo e cumprido o disposto no \u00a71\u00b0, o docente respons\u00e1vel pela disciplina divulgar\u00e1 o hor\u00e1rio e local de aplica\u00e7\u00e3o de nova prova ou de reposi\u00e7\u00e3o da aula, observando sempre o turno de aulas do discente, ou em contraturno, sendo necess\u00e1ria a anu\u00eancia expressa do discente. (Inclu\u00eddo pela <a href=\"https:\/\/bio.ufpr.br\/cbio\/wp-content\/uploads\/sites\/3\/2025\/05\/RESOLUCAO-No-42-22-CEPE.pdf\">Resolu\u00e7\u00e3o n\u00ba 42\/22-CEPE<\/a>)<br \/>\n\u00a73\u00b0 A crit\u00e9rio do docente respons\u00e1vel pela disciplina, a aplica\u00e7\u00e3o de nova prova ou a reposi\u00e7\u00e3o da aula poder\u00e1 ser substitu\u00edda por trabalho escrito ou outra modalidade de atividade de pesquisa a ser realizada pelo discente, com tema, objetivo e data de entrega definidos pelo docente. (Inclu\u00eddo pela <a href=\"https:\/\/bio.ufpr.br\/cbio\/wp-content\/uploads\/sites\/3\/2025\/05\/RESOLUCAO-No-42-22-CEPE.pdf\">Resolu\u00e7\u00e3o n\u00ba 42\/22-CEPE<\/a>)<\/p>\n<p style=\"padding-left: 40px\"><strong>Art. 83<\/strong> -As demais aus\u00eancias, justificadas ou n\u00e3o, dever\u00e3o ser computadas no limite m\u00e1ximo de vinte e cinco por cento (25%) de faltas permitido.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Procedimento de solicita\u00e7\u00e3o:<\/strong><\/p>\n<p>Preencha o <a href=\"https:\/\/bio.ufpr.br\/cbio\/wp-content\/uploads\/sites\/3\/2013\/07\/Dispensa_Frequencia.pdf\">Requerimento de Dispensa de Frequencia<\/a> com a justificativa de aus\u00eancia, anexe documentos comprobat\u00f3rios e envie para <a href=\"mailto:cbio@ufpr.br\">cbio@ufpr.br<\/a>. Ser\u00e1 aberto processo referente a sua solicita\u00e7\u00e3o, voc\u00ea ser\u00e1 comunicado por e-mail.<\/p>\n<hr \/>\n<h3>Exerc\u00edcios domiciliares<\/h3>\n<p><a href=\"https:\/\/bio.ufpr.br\/cbio\/wp-content\/uploads\/sites\/3\/2025\/03\/Res.-37-97-CEPE.pdf\">Resolu\u00e7\u00e3o 37\/97 &#8211; CEPE<\/a><\/p>\n<p style=\"padding-left: 40px\">Art. 84 -Ser\u00e1 permitido aos(\u00e0s) alunos(as) amparados(as) pelo Decreto-Lei n\u00ba 1044\/69 e \u00e0s alunas em estado de gravidez, nos termos da Lei n\u00ba 6202\/75, substituir a freq\u00fc\u00eancia \u00e0s aulas por<br \/>\nexerc\u00edcios domiciliares, sempre que a coordena\u00e7\u00e3o do curso, mediante consulta ao departamento se for o caso, entender como compat\u00edveis com o estado de sa\u00fade do requerente,<br \/>\ncom a natureza da disciplina e com as possibilidades da Institui\u00e7\u00e3o.<br \/>\nArt. 85 -Impossibilitado de freq\u00fcentar as aulas, o aluno ou seu representante requerer\u00e1 ao coordenador de seu curso, no prazo de at\u00e9 cinco 5 (cinco) dias \u00fateis contados do in\u00edcio do<br \/>\nimpedimento, o regime especial de exerc\u00edcios domiciliares, mediante apresenta\u00e7\u00e3o de atestado emitido por profissional da \u00e1rea de sa\u00fade.<\/p>\n<p style=\"padding-left: 80px\">\u00a7 1\u00ba &#8211; O coordenador de curso encaminhar\u00e1 a todos os departamentos que ministrem disciplinas para o interessado a autoriza\u00e7\u00e3o do regime de exerc\u00edcios domiciliares, quando for o<br \/>\ncaso.<br \/>\n\u00a7 2\u00ba &#8211; O aluno ou seu representante dever\u00e1 procurar nos departamentos as respectivas indica\u00e7\u00f5es dos exerc\u00edcios domiciliares, responsabilizando-se pelo cumprimento dos prazos<br \/>\nestabelecidos pelo(s) professor(es) da(s) disciplina(s).<br \/>\n\u00a7 3\u00ba &#8211; Nas disciplinas cuja natureza seja incompat\u00edvel com os exerc\u00edcios domiciliares, o aluno ter\u00e1, se necess\u00e1rio, mediante requerimento aprovado pelo colegiado do curso e enviado<br \/>\npela coordena\u00e7\u00e3o de curso ao SGA, sua matr\u00edcula removida no semestre\/ano em que ocorreu a incapacidade, visando salvaguardar o \u00cdndice de Rendimento Acumulado (I.R.A.) previsto no artigo 109 desta Resolu\u00e7\u00e3o.<\/p>\n<p><strong>Procedimento de solicita\u00e7\u00e3o:<\/strong><\/p>\n<p>Preencha o <a href=\"https:\/\/bio.ufpr.br\/cbio\/wp-content\/uploads\/sites\/3\/2025\/05\/Requerimento-Geral.pdf\">Requerimento Geral<\/a> com a justificativa de aus\u00eancia, anexe documentos comprobat\u00f3rios e envie para <a href=\"mailto:cbio@ufpr.br\">cbio@ufpr.br<\/a>. Ser\u00e1 aberto processo referente a sua solicita\u00e7\u00e3o, voc\u00ea ser\u00e1 comunicado por e-mail.<\/p>\n<p>&nbsp;<\/p>\n<p>Aten\u00e7\u00e3o ao prazo no calend\u00e1rio acad\u00eamico vigente.<\/p>\n<p>Refer\u00eancias:<\/p>\n<ul>\n<li><b>Resolu\u00e7\u00e3o 37\/97-CEPE\/UFPR<\/b>\u00a0(clique\u00a0<a href=\"http:\/\/www.soc.ufpr.br\/portal\/wp-content\/uploads\/2016\/07\/cepe-37-97-alterada-pela-Res-70-18.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"0\">Aqui<\/a>\u00a0para acessar).<\/li>\n<li><b>Decreto-Lei n\u00ba 1044\/69<\/b>\u00a0(clique\u00a0<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/decreto-lei\/del1044.htm\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"1\">Aqui<\/a>\u00a0para acessar).<\/li>\n<li><b>Lei N\u00ba 6.202\/75<\/b>\u00a0(clique\u00a0<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/1970-1979\/l6202.htm\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"2\">Aqui<\/a>\u00a0para acessar).<\/li>\n<\/ul>\n<hr \/>\n<p>Atualizado em: 17\/10\/2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dispensa de frequ\u00eancia Resolu\u00e7\u00e3o 37\/97 &#8211; CEPE Art. 80 &#8211;N\u00e3o haver\u00e1 abono de faltas, qualquer que tenha sido a raz\u00e3o da aus\u00eancia. Art. 81 -O coordenador do curso, de comum acordo com o(s) professor(es) ministrante(s) da(s) disciplina(s) cursada(s) pelo aluno, poder\u00e3o dispensar esporadicamente das aulas regulares o aluno participante de cursos intensivos, simp\u00f3sios, semin\u00e1rios, congressos, [&hellip;]<\/p>\n","protected":false},"author":2125,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-5275","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bio.ufpr.br\/cbio\/wp-json\/wp\/v2\/pages\/5275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bio.ufpr.br\/cbio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bio.ufpr.br\/cbio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bio.ufpr.br\/cbio\/wp-json\/wp\/v2\/users\/2125"}],"replies":[{"embeddable":true,"href":"https:\/\/bio.ufpr.br\/cbio\/wp-json\/wp\/v2\/comments?post=5275"}],"version-history":[{"count":14,"href":"https:\/\/bio.ufpr.br\/cbio\/wp-json\/wp\/v2\/pages\/5275\/revisions"}],"predecessor-version":[{"id":5809,"href":"https:\/\/bio.ufpr.br\/cbio\/wp-json\/wp\/v2\/pages\/5275\/revisions\/5809"}],"wp:attachment":[{"href":"https:\/\/bio.ufpr.br\/cbio\/wp-json\/wp\/v2\/media?parent=5275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}